{"id":1572,"date":"2024-07-18T21:34:46","date_gmt":"2024-07-18T19:34:46","guid":{"rendered":"http:\/\/campinglarochette.be\/?page_id=1572"},"modified":"2024-07-22T13:05:45","modified_gmt":"2024-07-22T11:05:45","slug":"payment-success","status":"publish","type":"page","link":"https:\/\/campinglarochette.be\/en\/payment-success\/","title":{"rendered":"Payment success"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-1572","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/campinglarochette.be\/en\/payment-success\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Camping La Rochette - Votre escapade entre Ardennes et Gaume\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Payment success - Camping La Rochette\" \/>\n\t\t<meta property=\"og:description\" content=\"Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/campinglarochette.be\/en\/payment-success\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/campinglarochette.be\/wp-content\/uploads\/2018\/08\/campterra_logo.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/campinglarochette.be\/wp-content\/uploads\/2018\/08\/campterra_logo.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"168\" \/>\n\t\t<meta property=\"og:image:height\" content=\"23\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-07-18T19:34:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-07-22T11:05:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Payment success - Camping La Rochette\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/campinglarochette.be\/wp-content\/uploads\/2018\/08\/campterra_logo.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/payment-success\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/payment-success\\\/#listItem\",\"name\":\"Payment success\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/payment-success\\\/#listItem\",\"position\":2,\"name\":\"Payment success\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/#organization\",\"name\":\"Camping La Rochette\",\"description\":\"Votre escapade entre Ardennes et Gaume\",\"url\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/campinglarochette.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo.png\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/payment-success\\\/#organizationLogo\",\"width\":250,\"height\":89},\"image\":{\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/payment-success\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/payment-success\\\/#webpage\",\"url\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/payment-success\\\/\",\"name\":\"Payment success - Camping La Rochette\",\"description\":\"Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/payment-success\\\/#breadcrumblist\"},\"datePublished\":\"2024-07-18T21:34:46+02:00\",\"dateModified\":\"2024-07-22T13:05:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/\",\"name\":\"Camping La Rochette\",\"description\":\"Votre escapade entre Ardennes et Gaume\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/campinglarochette.be\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Payment success - Camping La Rochette","description":"Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.","canonical_url":"https:\/\/campinglarochette.be\/en\/payment-success\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/campinglarochette.be\/en\/payment-success\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/campinglarochette.be\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/campinglarochette.be\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/campinglarochette.be\/en\/payment-success\/#listItem","name":"Payment success"}},{"@type":"ListItem","@id":"https:\/\/campinglarochette.be\/en\/payment-success\/#listItem","position":2,"name":"Payment success","previousItem":{"@type":"ListItem","@id":"https:\/\/campinglarochette.be\/en\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/campinglarochette.be\/en\/#organization","name":"Camping La Rochette","description":"Votre escapade entre Ardennes et Gaume","url":"https:\/\/campinglarochette.be\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/campinglarochette.be\/wp-content\/uploads\/2024\/07\/logo.png","@id":"https:\/\/campinglarochette.be\/en\/payment-success\/#organizationLogo","width":250,"height":89},"image":{"@id":"https:\/\/campinglarochette.be\/en\/payment-success\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/campinglarochette.be\/en\/payment-success\/#webpage","url":"https:\/\/campinglarochette.be\/en\/payment-success\/","name":"Payment success - Camping La Rochette","description":"Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/campinglarochette.be\/en\/#website"},"breadcrumb":{"@id":"https:\/\/campinglarochette.be\/en\/payment-success\/#breadcrumblist"},"datePublished":"2024-07-18T21:34:46+02:00","dateModified":"2024-07-22T13:05:45+02:00"},{"@type":"WebSite","@id":"https:\/\/campinglarochette.be\/en\/#website","url":"https:\/\/campinglarochette.be\/en\/","name":"Camping La Rochette","description":"Votre escapade entre Ardennes et Gaume","inLanguage":"en-US","publisher":{"@id":"https:\/\/campinglarochette.be\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Camping La Rochette - Votre escapade entre Ardennes et Gaume","og:type":"article","og:title":"Payment success - Camping La Rochette","og:description":"Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.","og:url":"https:\/\/campinglarochette.be\/en\/payment-success\/","og:image":"https:\/\/campinglarochette.be\/wp-content\/uploads\/2018\/08\/campterra_logo.svg","og:image:secure_url":"https:\/\/campinglarochette.be\/wp-content\/uploads\/2018\/08\/campterra_logo.svg","og:image:width":168,"og:image:height":23,"article:published_time":"2024-07-18T19:34:46+00:00","article:modified_time":"2024-07-22T11:05:45+00:00","twitter:card":"summary_large_image","twitter:title":"Payment success - Camping La Rochette","twitter:description":"Thank you for your payment. Your transaction has been completed and a receipt for your purchase has been emailed to you.","twitter:image":"https:\/\/campinglarochette.be\/wp-content\/uploads\/2018\/08\/campterra_logo.svg"},"aioseo_meta_data":{"post_id":"1572","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-07-18 19:34:46","updated":"2025-06-03 23:50:26","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/campinglarochette.be\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPayment success\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/campinglarochette.be\/en\/"},{"label":"Payment success","link":"https:\/\/campinglarochette.be\/en\/payment-success\/"}],"_links":{"self":[{"href":"https:\/\/campinglarochette.be\/en\/wp-json\/wp\/v2\/pages\/1572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campinglarochette.be\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campinglarochette.be\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campinglarochette.be\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campinglarochette.be\/en\/wp-json\/wp\/v2\/comments?post=1572"}],"version-history":[{"count":2,"href":"https:\/\/campinglarochette.be\/en\/wp-json\/wp\/v2\/pages\/1572\/revisions"}],"predecessor-version":[{"id":2156,"href":"https:\/\/campinglarochette.be\/en\/wp-json\/wp\/v2\/pages\/1572\/revisions\/2156"}],"wp:attachment":[{"href":"https:\/\/campinglarochette.be\/en\/wp-json\/wp\/v2\/media?parent=1572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}